{"id":59934,"date":"2015-03-24T19:18:09","date_gmt":"2015-03-24T17:18:09","guid":{"rendered":"https:\/\/moldovacrestina.md\/la-epistola-para-los-romanos-sobre-la-predestinacion"},"modified":"2017-05-03T18:02:13","modified_gmt":"2017-05-03T16:02:13","slug":"la-epistola-para-los-romanos-sobre-la-predestinacion","status":"publish","type":"post","link":"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/","title":{"rendered":"La-epistola-para-los-Romanos-sobre-la-predestinacion"},"content":{"rendered":"<p style=\"text-align: justify\">\n<p>pregunta<\/p>\n<blockquote class=\"td_quote_box td_box_center\">\n<p>\u00a0 \u00a0 \u00abQuiero preguntarlos que opinan sobre la predestinacion? Yo no creo en la predestinacion,pero de toda manera son algunos versiculos en la Biblia que confirma la existencia de la predestinacion. Por exemplo Romanos con los capitulos de 9 a 11. Usted que opina? Piensa que Dios a decidido antes que algunas personas se pierdan,y otras personas se salven, hagan lo que hagan cualquiera de ellos no pueden salir de la linea predestinado?\u00bb<\/p>\n<p style=\"text-align: left\"><img decoding=\"async\" class=\"aligncenter size-full img-resp\" src=\"https:\/\/cdn.moldovacrestina.md\/2018\/02\/294721_191196514282540_802248087_n.jpg\" alt=\"\"><\/p>\n<p>Es cierto que el texto de los capitulos 9-11 de la Epistola a los Romanos el apostol Pablo,en la primera lectura da la impresion de que hablan de la predestinacion. Muchos entienden este texto como una referencia al hecho de que desde el principio Dios predestino a unos para \u00a0vida eterna y otros para la perdicion eterna.<\/p>\n<p>Seguidores de la doctrina calvinista,que comparten esta doctrina de la predestinacion dice que la responsabilidad humana en la salvacion seria negar la soberania de Dios en un sentido el hombre por sus elecciones le obligaria a Dios actuar de una manera u otra. Sin embargo si hablamos de libre albedrio,la predestinacion contrario a lo largo \u00a0de la Biblia que Dios puso a hombre seguir antes de una eleccion y le informa que su destino sera adecuado con sus opciones. En el Antiguo Testamento Dios puso al hombre en la cara una opcion:cumplir la ley para ser bendecido en la tierra prometida, o si decide desobedecer los mandamientos de Dios sera maldecido en el pais,incluso al ser desterrado del pais.<\/p>\n<p>Mandamiento que Yo te mando hoy no es demasiado dificil para ti,ni esta lejos de ti. No esta en el Cielo para que digas\u00bbQuien subira al Cielo y lo tomara para nosotros,para que podamos oir y obedecer?\u00bb Ni esta al otro lado del mar para que digas:\u00bbQuien ira por nosotros mas alla del mar y nos llevara para que podamos oir y obedecer?\u00bb pero es my cerca de ti,en tu boca y en tu corazon \u00a0que cumples. Aqui Yo pongo hoy delante de ti la vida y el bien,la muerte y el mal. Porque Yo te mando hoy que ames a \u00a0Jehova tu Dios,que andes en Sus estatutos y Sus decretos,para que vivas y multiplicaos,y El Se\u00f1or tu Dios te bendecira en la tierra entras para poseerla. Pero si tu corazon se desvia,si usted no escucha y te dejas enga\u00f1ado a adorar otros dioses y servirles,les digo hoy que de cierto perecereis y vosotros no tendreis largos dias en la tierra que habeis de posesion despues de cruzar en Jordan. Al cielo y la tierra pongo por testigos contra vosotros que os he puesto delante la vida y la muerte,la bendecion y la maldicion. Escoge la vida para que vivas tu y tu descendencia a amar al Se\u00f1or tu Dios a obedecer Su voz y siguiendole a El,porque El que cuelga tu vida y la prolongacion de tus dias y la que habites en la tierra que Jehova juro a tus padres Abraham, Isaac y Jacob\u00bb ( Deuteronomio 30:19-20).<\/p>\n<p>Si hablamos de la nueva alianza el Nuevo Testamento deja claro que es la condicion de la salvacion-la fe.<\/p>\n<p>Porque tanto amo Dios al mundo que dio a Su Hijo unigenito para que todo aquel que en El cree no se pierda mas tenga vida eterna. Dios no envio a Su Hijo para condenar al mundo,sino para que el mundo se salve por medio de El. El que en El cree,no es condenado,pero que no cree ya a \u00a0sido condenado porque no ha creido en el nombre del Unigenito Hijo de Dios.(Juan3:16-18)<\/p>\n<p>Asi que la Nueva Alianza en comparacion con el antiguo pacto,las condiciones cambian:el hombre se salva por la fe ,no por obras de la ley (condicion de la Antigua Alianza)y la salvacion es para todos no solo para Israel. Si el nuevo pacto es un pacto condicionado que el hombre evidente tiene su parte de responsabilidad en la salvacion de su alma.<\/p>\n<h2>EL CONTEXTO DE ROMANOS 9-11<\/h2>\n<p>El contexto determina el significado del texto. Por eso es importante conocer el contexto de los tres capitulos de la Epistola a los \u00a0romanos, que parecerian que hablan de la predestinacion. Romanos fue escrita por Pablo Santo en Roma,que eran de hebreo y griego. La iglesia de Roma en ese momento se enfrento a dos herejias:<\/p>\n<p>Antinomicas(anti-en contra y nominal-ley) seguidores se esta ense\u00f1anza era contra la ley:se dice que la slvacion es \u00a0por gracia mediamente la fe,y por lo tanto el hombre puede vivir como piensa que quiere. Tal vez la mayoria de los seguidores de esta doctrina fueron gentiles.<\/p>\n<p>Judaizantes-pensban que la salvacion es por guardar la ley(el sistema de adoracion del Antiguo Pacto). En otras palabras eran de la opinion de que el Nuevo Pacto se a\u00f1ade a la Antigua Alianza y por lo tanto los cristianos deben guardar la ley que \u00abes la sombra del futuro y no la imagen mismas de las cosas\u00bb(Hebreos 10-1).<\/p>\n<p>\u00a0En esta carta,Pablo quiere combatir \u00a0estas herejias \u00a0de una manera muy sistematica.El libro se puede dividir en cinco segmentos:<\/p>\n<p>1:En los tres primeros capitulos(Romanos 1-3;20).El autor demuestra que todo el mundo(Judios y gentiles) estan bajo pecado y en la necesidad de la salvacion.<\/p>\n<p>2:Luego de 3:21 al capitulo 5,muestra que la salvacion es por fe sin las obras de la ley(es decir ,sin tomar el sistema de adoracion al Antiguo Pacto) para ambos Judios y gentiles<\/p>\n<p>3:En los capitulos 6-8 el apostol muestra que la \u00a0santificacion es el sacrificio de Jesucristo y la obra del Espiritu Santo en la vida de los salvados,no por obras de la ley(de mantenimiento de la Antigua Alianza)<\/p>\n<p>4:Luego en los siguientes capitulos del 9 al 11,el autor muestra la soberania de Dios en la salvacion: que El elige y como ahorrar. En otras palabras,Pablo demuestra que nadie podria entrar en culpa de Dios que El escogio salvar no solo el hebreo,sino tambien a los gentiles por la fe y no por obras de la ley.<\/p>\n<p>5:Los capitulos 12-16 son exhortaciones \u00a0practicas: como vivir la vida cristiana dado el trabajo que Dios esta \u00a0haciendo en el hombre nacido de nuevo.<\/p>\n<p><h2>DIOS NO DECIDE POR LOS HOMBRES PERO DECIDE SU DESTINO DE ACUERDO CON SUS ELECCIONES<\/p>\n<\/h2>\n<p>Confusion grande produce el capitulo 9, lo que parece que Dios decide a los humanos y no dejan espacio para la eleccion.Sin embargo,si estudiamos \u00a0cada caso,vemos que Dios escoge a quien tenga misericordia,de acuerdo con la decisiones que toman al hombre \u00a0a su conocimientos antes. Por ejemplo, porque Dios amo a Jacob y odio a Esau?En el Genesis encontramos la respuesta: Jacob atesoraba mas que todos los bendiciones de Dios pero no a Esau. Esau vendio su bendicion que tenia el derecho \u00a0primogenito por unplato de lentejas. Otro ejemplo es el de Faraon. En el libro de Exodo 7-11 encontramos que los primeros 5 plagas Faraon endurecio su corazon solo y no queria dejar ir al pueblo y solo la sexta plaga Dios endurecio su corazon y le dijo:<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00bb Si \u00a0Yo hubiera extendido Mi mano te hubiera golpeado con pestilencia,a ti y a tu gente que habria muerto de la tierra.Pero te deje permanecer de pie,para mostrarte Mi poder y para que Mi nombre sea anunciado en toda la tierra.\u00bb(Exodo 9:15-16)<\/p>\n<p>Es decir Pablo cita este texto en Romanos 9-17. Si el texto de Romanos muchos concluyo que Dios a hecho a proposito de herir a Faraon endurecio su corazon ,entonces el texto en el libro de Exodo entendemos que Dios levanto a Faraon \u00a0en que lo dejo con vida y no destruido.No Dios lo hizo mal ,Dios lo levanto donde estaba y lo dejo con vida.<\/p>\n<p><h2>PALABRA \u00abPREDESTINACION\u00bb EN LA BIBLIA<\/p>\n<\/h2>\n<p>La palabra\u00bbpredestinado\u00bb en la Biblia se usa cinco veces en tres epistolas \u00a0del apostol Pablo se tradujo al rumano por la expreciones \u00abpredestinado\u00bb.Mediante el estudio de estos textos,entendemos que Dios decide el destino del hombre del antemano segun el previo conocimiento de su eleccion.<\/p>\n<p>1:En Romanos \u00a08:28-30 Dios dice que El predestino a quien Su semejanza y por que esta llamndo.Del contexto entendemos que Dios a predestinado para que la imagen de Su Hijo a los que antes conocio que lo amara.<\/p>\n<p>\u00a0Por otro lado ,sabemos que todas las cosas les ayudan a bien a los que aman a Dios, es decir a los que son llamados conforme a su proposito. Porque a los que de antemano conocio tambien los predestino a ser transformados segun la imagen de Su Hijo,para que El sea El primogenito entre muchos hermanos.Y a los que \u00a0predestino a estos tambien justifico y los que justifico a estos tambien glorifico.(Romanos 8:28-29).<\/p>\n<p>2:Efesios \u00a01:15, 11 Aqui la palabra se traduce \u00abpredestinado\u00bb.<\/p>\n<p>En El,Dios \u00a0nos escogio antes de la fundacion del mundo para ser santos y sin mancha delante de el cuando en el amor nos exponemos a ser adopcion como hijos adoptivos por medio de Jesucristo segun el puro de Su voluntad (Efesios 1:5). En El asimismo tuvimos herencia ,habiendo sido predestinados conforme al proposito del que hace todas las cosas segun el designio de su voluntad ,para alabanza de Su gloria que primeramente esperabamos en Cristo. Y vosotros habiendo oido la palabra de verdad (el evangelio de vuestra salvacion ),han creido en El ,fuisteis sellados con Espiritu Santo de la promesa,que es las arras \u00a0de nuestra herencia ,para la redencion de la posesion adquirida,para \u00a0alabanza Su gloria.(Efesios 1:11-14).<\/p>\n<p>Vemos que ellos\u00bbhan sido predestinados para ser adoptados hijos Suyos \u00a0por medio de Jesucristo\u00bb destinatarios que,primeramente esperabamos en Cristo y tener la autoridad especifica de que han oido el evangelio,creyeron y fueron sellados con El Espiritu Santo. Esto es muy importante porque la doctrina calvinista que ense\u00f1a que Dios predestino a algunos a la destruccion eterna y a otros para la salvacion,dice que el hombre es tan pecaminoso(depravacion total) que el es incapaz de llegar al arrepentimiento,solo Dios y el hombre regenerado (es decir sellados con Epiritu Santo) pueden recibir el evangelio cuando oye.En otras palabras segun este primer hombre ense\u00f1anza es regenerado(nacido de nuevo) y luego escucha el evangelio y creer.<\/p>\n<p>\u00a0 Asi que Dios es soberano y El tiene todo bajo control y en su soberania ,se decidio por quien y que criterios \u00a0de ahorrar ,pero no excluye la responsabilidad<\/p>\n<p>humana en la salvacion.<\/p>\n<p>\u00a0 \u00a0 Le recomiendo que leea tambien el articulo \u00abLa ense\u00f1anza de apoyo biblico de la eleccion incondicional\u00bb.<\/p>\n<p>\u00a0 traducido por Crina Catana<\/p>\n","protected":false},"excerpt":{"rendered":"<p>pregunta \u00a0 \u00a0 \u00abQuiero preguntarlos que opinan sobre la predestinacion? Yo no creo en la predestinacion,pero de toda manera son algunos versiculos en la Biblia que confirma la existencia de la predestinacion. Por exemplo Romanos con los capitulos de 9 a 11. Usted que opina? Piensa que Dios a decidido antes que algunas personas se [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":107512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","ep_embedding_exclude":false,"ep_embedding_include":false,"ep_exclude_from_search":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[29341],"tags":[11385],"class_list":["post-59934","post","type-post","status-publish","format-standard","has-post-thumbnail","category-respuestas-de-la-palabra","tag-predestinacion-romanos-antiguo-pacto-el-nuevo-pacto-predestinados-antinomicas-judaizantes","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.5 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dios-elige-a-la-presciencia-de-corazon-humano<\/title>\n<meta name=\"description\" content=\"Dios-decidio-el-destino-del-hombre-a-traves-de-su-conocimiento-previo-de-su-corazon-Dios-decide-el-destino-del-hombre-pero-no-sus-opciones\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La-epistola-para-los-Romanos-sobre-la-predestinacion\" \/>\n<meta property=\"og:description\" content=\"Dios-decidio-el-destino-del-hombre-a-traves-de-su-conocimiento-previo-de-su-corazon-Dios-decide-el-destino-del-hombre-pero-no-sus-opciones\" \/>\n<meta property=\"og:url\" content=\"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Moldova Cre\u0219tin\u0103\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/moldovacrestina\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-24T17:18:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-03T16:02:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.moldovacrestina.md\/2016\/10\/294721_191196514282540_802248087_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anastasia Filat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@moldovacrestina\" \/>\n<meta name=\"twitter:site\" content=\"@moldovacrestina\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anastasia Filat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/la-epistola-para-los-romanos-sobre-la-predestinacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/la-epistola-para-los-romanos-sobre-la-predestinacion\\\/\"},\"author\":{\"name\":\"Anastasia Filat\",\"@id\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/#\\\/schema\\\/person\\\/2ee75aca099062ac8880ffa7575a4aeb\"},\"headline\":\"La-epistola-para-los-Romanos-sobre-la-predestinacion\",\"datePublished\":\"2015-03-24T17:18:09+00:00\",\"dateModified\":\"2017-05-03T16:02:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/la-epistola-para-los-romanos-sobre-la-predestinacion\\\/\"},\"wordCount\":1786,\"image\":{\"@id\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/la-epistola-para-los-romanos-sobre-la-predestinacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/moldovacrestina.md\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/294721_191196514282540_802248087_n.jpg\",\"keywords\":[\"predestinacion-romanos-antiguo-pacto-el-nuevo-pacto-predestinados-antinomicas-judaizantes\"],\"articleSection\":[\"Respuestas de la Palabra\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/la-epistola-para-los-romanos-sobre-la-predestinacion\\\/\",\"url\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/la-epistola-para-los-romanos-sobre-la-predestinacion\\\/\",\"name\":\"Dios-elige-a-la-presciencia-de-corazon-humano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/la-epistola-para-los-romanos-sobre-la-predestinacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/la-epistola-para-los-romanos-sobre-la-predestinacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/moldovacrestina.md\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/294721_191196514282540_802248087_n.jpg\",\"datePublished\":\"2015-03-24T17:18:09+00:00\",\"dateModified\":\"2017-05-03T16:02:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/#\\\/schema\\\/person\\\/2ee75aca099062ac8880ffa7575a4aeb\"},\"description\":\"Dios-decidio-el-destino-del-hombre-a-traves-de-su-conocimiento-previo-de-su-corazon-Dios-decide-el-destino-del-hombre-pero-no-sus-opciones\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/la-epistola-para-los-romanos-sobre-la-predestinacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/la-epistola-para-los-romanos-sobre-la-predestinacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/la-epistola-para-los-romanos-sobre-la-predestinacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/moldovacrestina.md\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/294721_191196514282540_802248087_n.jpg\",\"contentUrl\":\"https:\\\/\\\/moldovacrestina.md\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/294721_191196514282540_802248087_n.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/la-epistola-para-los-romanos-sobre-la-predestinacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Doctrina\",\"item\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/\\\/doctrina-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La-epistola-para-los-Romanos-sobre-la-predestinacion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/\",\"name\":\"Moldova Cre\u0219tin\u0103\",\"description\":\"R\u0103spunsuri relevante \u0219i actuale din Biblie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/#\\\/schema\\\/person\\\/2ee75aca099062ac8880ffa7575a4aeb\",\"name\":\"Anastasia Filat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50c6c7c3ea8d39be8e58ea9617c8e1b8f9be234289757ef7156664ff8e090478?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50c6c7c3ea8d39be8e58ea9617c8e1b8f9be234289757ef7156664ff8e090478?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50c6c7c3ea8d39be8e58ea9617c8e1b8f9be234289757ef7156664ff8e090478?s=96&d=mm&r=g\",\"caption\":\"Anastasia Filat\"},\"description\":\"Sunt mam\u0103 a 3 copii \u0219i profesoar\u0103 \u00een cadrul Institutului de Studii Biblice Inductive din Moldova. De asemenea, \u00eel ajut pe so\u021bul meu, Vasile Filat, \u00een p\u0103storirea Bisericii \\\"Buna Vestire\\\" din Chi\u0219in\u0103u.\",\"url\":\"https:\\\/\\\/moldovacrestina.md\\\/es\\\/author\\\/filat-nastica\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dios-elige-a-la-presciencia-de-corazon-humano","description":"Dios-decidio-el-destino-del-hombre-a-traves-de-su-conocimiento-previo-de-su-corazon-Dios-decide-el-destino-del-hombre-pero-no-sus-opciones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/","og_locale":"es_ES","og_type":"article","og_title":"La-epistola-para-los-Romanos-sobre-la-predestinacion","og_description":"Dios-decidio-el-destino-del-hombre-a-traves-de-su-conocimiento-previo-de-su-corazon-Dios-decide-el-destino-del-hombre-pero-no-sus-opciones","og_url":"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/","og_site_name":"Moldova Cre\u0219tin\u0103","article_publisher":"https:\/\/www.facebook.com\/moldovacrestina\/","article_published_time":"2015-03-24T17:18:09+00:00","article_modified_time":"2017-05-03T16:02:13+00:00","og_image":[{"width":600,"height":350,"url":"https:\/\/cdn.moldovacrestina.md\/2016\/10\/294721_191196514282540_802248087_n.jpg","type":"image\/jpeg"}],"author":"Anastasia Filat","twitter_card":"summary_large_image","twitter_creator":"@moldovacrestina","twitter_site":"@moldovacrestina","twitter_misc":{"Escrito por":"Anastasia Filat","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/#article","isPartOf":{"@id":"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/"},"author":{"name":"Anastasia Filat","@id":"https:\/\/moldovacrestina.md\/es\/#\/schema\/person\/2ee75aca099062ac8880ffa7575a4aeb"},"headline":"La-epistola-para-los-Romanos-sobre-la-predestinacion","datePublished":"2015-03-24T17:18:09+00:00","dateModified":"2017-05-03T16:02:13+00:00","mainEntityOfPage":{"@id":"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/"},"wordCount":1786,"image":{"@id":"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/#primaryimage"},"thumbnailUrl":"https:\/\/moldovacrestina.md\/wp-content\/uploads\/2016\/10\/294721_191196514282540_802248087_n.jpg","keywords":["predestinacion-romanos-antiguo-pacto-el-nuevo-pacto-predestinados-antinomicas-judaizantes"],"articleSection":["Respuestas de la Palabra"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/","url":"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/","name":"Dios-elige-a-la-presciencia-de-corazon-humano","isPartOf":{"@id":"https:\/\/moldovacrestina.md\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/#primaryimage"},"image":{"@id":"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/#primaryimage"},"thumbnailUrl":"https:\/\/moldovacrestina.md\/wp-content\/uploads\/2016\/10\/294721_191196514282540_802248087_n.jpg","datePublished":"2015-03-24T17:18:09+00:00","dateModified":"2017-05-03T16:02:13+00:00","author":{"@id":"https:\/\/moldovacrestina.md\/es\/#\/schema\/person\/2ee75aca099062ac8880ffa7575a4aeb"},"description":"Dios-decidio-el-destino-del-hombre-a-traves-de-su-conocimiento-previo-de-su-corazon-Dios-decide-el-destino-del-hombre-pero-no-sus-opciones","breadcrumb":{"@id":"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/#primaryimage","url":"https:\/\/moldovacrestina.md\/wp-content\/uploads\/2016\/10\/294721_191196514282540_802248087_n.jpg","contentUrl":"https:\/\/moldovacrestina.md\/wp-content\/uploads\/2016\/10\/294721_191196514282540_802248087_n.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/moldovacrestina.md\/es\/la-epistola-para-los-romanos-sobre-la-predestinacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/moldovacrestina.md\/es\/"},{"@type":"ListItem","position":2,"name":"Doctrina","item":"https:\/\/moldovacrestina.md\/es\/\/doctrina-es\/"},{"@type":"ListItem","position":3,"name":"La-epistola-para-los-Romanos-sobre-la-predestinacion"}]},{"@type":"WebSite","@id":"https:\/\/moldovacrestina.md\/es\/#website","url":"https:\/\/moldovacrestina.md\/es\/","name":"Moldova Cre\u0219tin\u0103","description":"R\u0103spunsuri relevante \u0219i actuale din Biblie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/moldovacrestina.md\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/moldovacrestina.md\/es\/#\/schema\/person\/2ee75aca099062ac8880ffa7575a4aeb","name":"Anastasia Filat","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/50c6c7c3ea8d39be8e58ea9617c8e1b8f9be234289757ef7156664ff8e090478?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50c6c7c3ea8d39be8e58ea9617c8e1b8f9be234289757ef7156664ff8e090478?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50c6c7c3ea8d39be8e58ea9617c8e1b8f9be234289757ef7156664ff8e090478?s=96&d=mm&r=g","caption":"Anastasia Filat"},"description":"Sunt mam\u0103 a 3 copii \u0219i profesoar\u0103 \u00een cadrul Institutului de Studii Biblice Inductive din Moldova. De asemenea, \u00eel ajut pe so\u021bul meu, Vasile Filat, \u00een p\u0103storirea Bisericii \"Buna Vestire\" din Chi\u0219in\u0103u.","url":"https:\/\/moldovacrestina.md\/es\/author\/filat-nastica\/"}]}},"video_meta":false,"featured_image":"https:\/\/moldovacrestina.md\/wp-content\/uploads\/2016\/10\/294721_191196514282540_802248087_n.jpg","wpml":{"language_code":"es","locale":"es_ES","text_direction":false,"display_name":"Espa\u00f1ol","native_name":"Spaniol\u0103","different_language":false},"jetpack-related-posts":[{"id":54239,"url":"https:\/\/moldovacrestina.md\/es\/liberacion-maldiciones-brujos\/","url_meta":{"origin":59934,"position":0},"title":"\u00bfC\u00f3mo librarse de las maldiciones de los hechiceros?","author":"Vasile Filat","date":"24 de mayo de 2015","format":false,"excerpt":"He recibido la siguiente pregunta, que contestar\u00e9 en este art\u00edculo: Mi pregunta est\u00e1 relacionada con las personas que se ocupan con el ocultismo, brujer\u00edas, maldiciones. Tengo un familiar muy cercano a mi familia, que se ocupa con estas cosas desde hace muchos a\u00f1os, por envidia y pienso, por codicia y\u2026","rel":"","context":"<span class=\"jp-relatedposts-post-author\">Vasile Filat<\/span>","block_context":{"text":"Respuestas de la Palabra","link":"https:\/\/moldovacrestina.md\/es\/respuestas-de-la-palabra\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/cdn.moldovacrestina.md\/2015\/05\/l.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":81098,"url":"https:\/\/moldovacrestina.md\/es\/acerca-de-las-oraciones-por-los-muertos\/","url_meta":{"origin":59934,"position":1},"title":"Tema acerca de las oraciones por los muertos","author":"Vasile Filat","date":"13 de diciembre de 2011","format":false,"excerpt":"Yo he recibido la siguiente pregunta de un lector de nuestro portal. \u00bfQu\u00e9 opini\u00f3n tiene usted acerca de las oraciones por los que est\u00e1n muertos \u00bfEs normal que un cristiano crea en estas oraciones o es malo? \u00bfPuede esto afectar mi relaci\u00f3n con Dios? \u00bfQu\u00e9 pasa con los pasajes b\u00edblicos\u2026","rel":"","context":"<span class=\"jp-relatedposts-post-author\">Vasile Filat<\/span>","block_context":{"text":"Respuestas de la Palabra","link":"https:\/\/moldovacrestina.md\/es\/respuestas-de-la-palabra\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":81149,"url":"https:\/\/moldovacrestina.md\/es\/dios-no-es-el-creador-del-mal\/","url_meta":{"origin":59934,"position":2},"title":"Dios no es el creador del mal","author":"Vasile Filat","date":"19 de diciembre de 2011","format":false,"excerpt":"Como te he prometido ayer, hoy voy a responder a la siguiente pregunta que\u00a0 me pidi\u00f3 \u00a0un lector del portal: \u00bfPor qu\u00e9 Dios cre\u00f3 al diablo y el infierno? Desde el principio pens\u00e9 que pod\u00eda responder a esta pregunta en un art\u00edculo, pero la pregunta es demasiado amplia. \u00a0Hoy \u00a0invito\u2026","rel":"","context":"<span class=\"jp-relatedposts-post-author\">Vasile Filat<\/span>","block_context":{"text":"Respuestas de la Palabra","link":"https:\/\/moldovacrestina.md\/es\/respuestas-de-la-palabra\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":81553,"url":"https:\/\/moldovacrestina.md\/es\/como-deshacerse-del-odio\/","url_meta":{"origin":59934,"position":3},"title":"\u00bf Como  deshacerse del odio?","author":"Vasile Filat","date":"14 de marzo de 2012","format":false,"excerpt":"Esta pregunta fue hecha\u00a0 a trav\u00e9s de nuestro servicio de chat , una pregunta corta con una respuesta larga. \u00bf C\u00f3mo deshacerse del odio? Al igual como\u00a0 todos los pecados\u00a0 en primer lugar\u2026 Identifica el origen de su odio Establece\u00a0 un tiempo, entra en una habitaci\u00f3n tranquila, o encuentra un\u2026","rel":"","context":"<span class=\"jp-relatedposts-post-author\">Vasile Filat<\/span>","block_context":{"text":"Respuestas de la Palabra","link":"https:\/\/moldovacrestina.md\/es\/respuestas-de-la-palabra\/"},"img":{"alt_text":"\u00bf Como  deshacerse del odio?","src":"https:\/\/i0.wp.com\/cdn.moldovacrestina.md\/2012\/03\/depression_by_3rd3m.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cdn.moldovacrestina.md\/2012\/03\/depression_by_3rd3m.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cdn.moldovacrestina.md\/2012\/03\/depression_by_3rd3m.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cdn.moldovacrestina.md\/2012\/03\/depression_by_3rd3m.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":81176,"url":"https:\/\/moldovacrestina.md\/es\/personas-influidas-mal\/","url_meta":{"origin":59934,"position":4},"title":"\u00bfC\u00f3mo las personas han sido influidas por el mal?","author":"Vasile Filat","date":"22 de diciembre de 2011","format":false,"excerpt":"El mal que se manifest\u00f3 en el exterior, es el resultado del mal que se encuentra en el coraz\u00f3n de la gente en su naturaleza pecaminosa.\u00a0 \u00bfComo han llegado a este estado? Este ser\u00e1 el tema del art\u00edculo de hoy. El diablo estaba y est\u00e1 interesado en destruir a la\u2026","rel":"","context":"<span class=\"jp-relatedposts-post-author\">Vasile Filat<\/span>","block_context":{"text":"Respuestas de la Palabra","link":"https:\/\/moldovacrestina.md\/es\/respuestas-de-la-palabra\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":51687,"url":"https:\/\/moldovacrestina.md\/es\/acerca-de-la-adoracion-de-los-iconos\/","url_meta":{"origin":59934,"position":5},"title":"Que dice la Biblia acerca de los iconos y la adoracion de ellos!","author":"Vasile Filat","date":"23 de marzo de 2015","format":false,"excerpt":"Pregunta: Que es un icono? Esta bien adorar o hacer la cruz delante del icono? La palabra \"icono \" es una palabra de Grecia que la usamos tambien en rumano y significa \"imagen\". La primera pregunta que es un icono.Nosotros somos gente ortodoxo y los vemos siempre,estan en casas,en las\u2026","rel":"","context":"<span class=\"jp-relatedposts-post-author\">Vasile Filat<\/span>","block_context":{"text":"Respuestas de la Palabra","link":"https:\/\/moldovacrestina.md\/es\/respuestas-de-la-palabra\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/cdn.moldovacrestina.md\/2015\/03\/2690406770_046513e9d4.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/moldovacrestina.md\/wp-content\/uploads\/2016\/10\/294721_191196514282540_802248087_n.jpg","_links":{"self":[{"href":"https:\/\/moldovacrestina.md\/es\/wp-json\/wp\/v2\/posts\/59934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moldovacrestina.md\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moldovacrestina.md\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moldovacrestina.md\/es\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/moldovacrestina.md\/es\/wp-json\/wp\/v2\/comments?post=59934"}],"version-history":[{"count":0,"href":"https:\/\/moldovacrestina.md\/es\/wp-json\/wp\/v2\/posts\/59934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moldovacrestina.md\/es\/wp-json\/wp\/v2\/media\/107512"}],"wp:attachment":[{"href":"https:\/\/moldovacrestina.md\/es\/wp-json\/wp\/v2\/media?parent=59934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moldovacrestina.md\/es\/wp-json\/wp\/v2\/categories?post=59934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moldovacrestina.md\/es\/wp-json\/wp\/v2\/tags?post=59934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}